{"id":969,"date":"2011-01-04T03:54:51","date_gmt":"2011-01-04T03:54:51","guid":{"rendered":"http:\/\/enriquecetupsicologia.com\/articulos\/?p=969"},"modified":"2021-02-09T16:13:43","modified_gmt":"2021-02-09T22:13:43","slug":"administracion-del-conocimiento","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/969\/administracion-del-conocimiento\/","title":{"rendered":"Administraci\u00f3n del conocimiento"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"969\" class=\"elementor elementor-969\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bd47fbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bd47fbb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d228f65\" data-id=\"1d228f65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f950b11 elementor-widget elementor-widget-text-editor\" data-id=\"5f950b11\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Administraci\u00f3n del conocimiento<\/h1><h2>C\u00f3mo transformar el conocimiento en acci\u00f3n.<\/h2><p>EL SABER NO ES PROPORCIONAL AL HACER, es decir podr\u00edas haber asistido a muchos seminarios y capacitaciones, incluso ser graduado de una universidad prestigiosa y no tener la capacidad de llevar toda esa calidad de conocimiento a la acci\u00f3n; hablar sobre cosas inteligentes y conversar al respecto no es suficiente para obtener resultados.<\/p><p>Existe por lo tanto un \u00abdivorcio\u00bb entre el saber y el hacer, una distancia que analizamos en esta serie de videos, <span style=\"color: #ff0000;\">pero lo m\u00e1s importante <\/span><strong>BRINDAMOS TECNICAS<\/strong> que sirven para minimizar al m\u00e1ximo\u00a0esta brecha\u00a0para lograr aprovechar los recursos que se invierten en capacitaciones, entrenamientos y educaci\u00f3n en general.<\/p><p><a href=\"http:\/\/enriquecetupsicologia.com\/articulos\/wp-content\/uploads\/2011\/01\/Como-transformar-el-conocimiento-en-accion.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-972\" title=\"Como transformar el conocimiento en accion\" src=\"http:\/\/enriquecetupsicologia.com\/articulos\/wp-content\/uploads\/2011\/01\/Como-transformar-el-conocimiento-en-accion-300x226.jpg\" alt=\"\" width=\"304\" height=\"184\" \/><\/a><\/p><p>En este video repasamos las t\u00e9cnicas:<\/p><p>1- Dise\u00f1o de metas adecuados (Auto-expectativa de logro).<\/p><p>2-Compromiso social.<\/p><p>3- Asociaci\u00f3n del hecho con otro de gusto personal.<\/p><p><object width=\"425\" height=\"344\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/LIToOzqVwZk?fs=1&amp;hl=es_ES&amp;rel=0&amp;color1=0x2b405b&amp;color2=0x6b8ab6\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"425\" height=\"344\" src=\"http:\/\/www.youtube.com\/v\/LIToOzqVwZk?fs=1&amp;hl=es_ES&amp;rel=0&amp;color1=0x2b405b&amp;color2=0x6b8ab6\" allowfullscreen=\"allowfullscreen\" allowscriptaccess=\"always\" \/><\/object><br \/>.<\/p><h5 style=\"text-align: center;\">\u00a0<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0db6f81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0db6f81\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55455f1\" data-id=\"55455f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3ac0d1 elementor-widget elementor-widget-image\" data-id=\"d3ac0d1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"653\" height=\"758\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/07\/1d.jpg\" class=\"attachment-large size-large wp-image-2996\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/07\/1d.jpg 653w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/07\/1d-258x300.jpg 258w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-599d483 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"599d483\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44733b1\" data-id=\"44733b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee2e9be elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ee2e9be\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dae6981 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dae6981\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92891ee\" data-id=\"92891ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e6d64e elementor-widget elementor-widget-spacer\" data-id=\"3e6d64e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Existe  una brecha  entre el saber y el hacer que analizamos en esta serie de videos, BRINDAMOS TECNICAS para minimizar al m\u00e1ximo la brecha entre el saber y el hacer<\/p>\n","protected":false},"author":3,"featured_media":1184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,50,1],"tags":[30,38],"class_list":["entry","author-eduardo-gomez-director","has-excerpt","post-969","post","type-post","status-publish","format-standard","has-post-thumbnail","category-administracion-del-talento-humano-2","category-capacitacion-recursos-humanos-2","category-mandos-medios","tag-administracion-del-talento-humano","tag-ejemplos-de-motivacion"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=969"}],"version-history":[{"count":9,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/969\/revisions"}],"predecessor-version":[{"id":4137,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/969\/revisions\/4137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/1184"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}