{"id":77,"date":"2010-08-24T17:31:13","date_gmt":"2010-08-24T17:31:13","guid":{"rendered":"http:\/\/enriquecetupsicologia.com\/articulos\/?p=77"},"modified":"2021-02-09T16:18:10","modified_gmt":"2021-02-09T22:18:10","slug":"factores-del-exito","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/77\/factores-del-exito\/","title":{"rendered":"Factores del \u00e9xito"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"77\" class=\"elementor elementor-77\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70b525ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70b525ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66630b6c\" data-id=\"66630b6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65597dd3 elementor-widget elementor-widget-text-editor\" data-id=\"65597dd3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"http:\/\/enriquecetupsicologia.com\/articulos\/wp-content\/uploads\/2010\/08\/bed.png\"><img decoding=\"async\" class=\"size-thumbnail wp-image-153 aligncenter\" title=\"bed\" src=\"http:\/\/enriquecetupsicologia.com\/articulos\/wp-content\/uploads\/2010\/08\/bed-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p><p>\u00a0<span style=\"color: #ff6600;\">La disciplina de acomodar tu cama todos los d\u00edas es la misma que necesitas para tener \u00e9xito en la vida y en tu empresa.<\/span><\/p><p>La principal caracter\u00edstica de la disciplina es la constancia y \u00e9sta no puede ser inconstante, <span style=\"color: #b70000;\">en otras palabras no puede ser que en tu trabajo tengas disciplina pero al llegar a tu casa se te olvida,<\/span> y vives tus d\u00edas encendiendo el TV o la computadora por horas dejando pasar el tiempo.<\/p><p>He escuchado algunas amistades decir \u201ccuando yo quiero lo hago\u201d y de verdad que lo pueden hacer; y eso los hace sentir bien porque realmente son capaces de poder hacerlo, pero de una forma inconstante. <span style=\"text-decoration: underline;\">El problema de una disciplina y capacidad inconstante es que se pasan los d\u00edas y a\u00fan no has terminado tu proyecto<\/span>, se acercan las fechas l\u00edmites de entrega y a \u00faltimo momento debes andar corriendo.<\/p><p>Ser disciplinado cuesta, ya que es m\u00e1s f\u00e1cil encender la computadora que apagarla, comprar algo r\u00e1pido para comer que hacerse algo saludable, es m\u00e1s f\u00e1cil \u201cdejarlo para ma\u00f1ana\u201d; <strong>\u00bflo ves? Hay una gran diferencia en pasar haciendo solamente lo que nos gusta en pasar haciendo lo que nos conviene,<\/strong> todas las personas tenemos 24 horas al d\u00eda y lo que diferencia el avance de unas respecto a otras es la forma en como organizan sus actividades en su tiempo.<\/p><p>Deseo que hoy te repitas durante el d\u00eda \u00e9sta frase (incluso estando en tu casa despu\u00e9s del trabajo): <span style=\"text-decoration: underline;\"><strong>\u201cLa disciplina no puede ser inconstante\u201d.<\/strong><\/span><\/p><p>S\u00f3lo el hecho de decirlo varias veces con tu boca tendr\u00e1 la capacidad de cambiar algo en tu d\u00eda en pro de tus metas, <strong>pero s\u00f3lo lo experimentar\u00e1s, si lo haces.<\/strong><\/p><h5 style=\"text-align: center;\">\u00a0<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b6785a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b6785a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-261038b\" data-id=\"261038b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1618a4b elementor-widget elementor-widget-image\" data-id=\"1618a4b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-724x1024.jpg\" class=\"attachment-large size-large wp-image-3062\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-724x1024.jpg 724w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-212x300.jpg 212w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-768x1086.jpg 768w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f43f358 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f43f358\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e2039b\" data-id=\"0e2039b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6582d53 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6582d53\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e31453 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e31453\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a33334b\" data-id=\"a33334b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c26adcf elementor-widget elementor-widget-spacer\" data-id=\"c26adcf\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ser disciplinado cuesta, ya que es m\u00e1s f\u00e1cil encender la computadora que apagarla, comprar algo r\u00e1pido para comer que hacerse algo saludable, es m\u00e1s f\u00e1cil \u201cdejarlo para ma\u00f1ana\u201d; \u00bflo ves? Hay una gran diferencia en pasar haciendo solamente lo que nos gusta en pasar haciendo lo que nos conviene, todas las personas tenemos 24 horas al d\u00eda y lo que diferencia el avance&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,1],"tags":[30,61],"class_list":["entry","author-eduardo-gomez-director","has-excerpt","post-77","post","type-post","status-publish","format-standard","has-post-thumbnail","category-administracion-del-talento-humano-2","category-mandos-medios","tag-administracion-del-talento-humano","tag-mandos-medios-2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=77"}],"version-history":[{"count":9,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/77\/revisions"}],"predecessor-version":[{"id":4173,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/77\/revisions\/4173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/1234"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=77"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=77"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}