{"id":4516,"date":"2024-01-27T19:36:48","date_gmt":"2024-01-28T01:36:48","guid":{"rendered":"https:\/\/www.psicologialaboral.net\/articulos\/?p=4516"},"modified":"2024-05-16T20:10:16","modified_gmt":"2024-05-17T02:10:16","slug":"%f0%9f%94%91-herramienta-de-coaching-escalera-de-logros","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/4516\/%f0%9f%94%91-herramienta-de-coaching-escalera-de-logros\/","title":{"rendered":"\ud83d\udd11 Herramienta de Coaching: Escalera de logros."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4516\" class=\"elementor elementor-4516\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8960ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8960ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a43ac2e\" data-id=\"a43ac2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dcf17c elementor-widget elementor-widget-text-editor\" data-id=\"3dcf17c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0llevame al sircoo. De la pradera ullamco qu\u00e9 dise usteer est\u00e1 la cosa muy malar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e93be91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e93be91\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85b9e4d\" data-id=\"85b9e4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48b6728 elementor-widget elementor-widget-text-editor\" data-id=\"48b6728\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\ud83e\ude9c Dividir las metas en pasos m\u00e1s peque\u00f1os y manejables afecta positivamente el desempe\u00f1o de la misma.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9d7d48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9d7d48\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-815a271\" data-id=\"815a271\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21d8a29 elementor-widget elementor-widget-text-editor\" data-id=\"21d8a29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00abQuiero bajar de peso\u00bb<\/strong><\/p><p><strong>\u00abQuiero terminar mis estudios\u00bb<\/strong><\/p><p><strong>\u00abQuiero certificarme como coach\u00bb<\/strong><\/p><p><strong>\u00abQuiero invertir mis ahorros\u00bb<\/strong><\/p><p><strong>Etc.<\/strong><\/p><p>\u00a0<\/p><p>Son metas que no te van a mover a la acci\u00f3n, sabes \u00bfPorqu\u00e9? Porque la mente requiere claridad de pensamiento para facilitar la ejecuci\u00f3n.<\/p><p>\u00a0<\/p><p>Por ejemplo ya sabemos que las metras generales no funcionan, funcionan mejor las espec\u00edficas, la que tienen una dificultad moderada y las que son manejables para nuestra mente.<\/p><p>\u00a0<\/p><p><i>Locke, E. A., &amp; Latham, G. P. (2002). Building a practically useful theory of goal setting and task motivation: A 35-year odyssey. American Psychologist, 57(9), 705\u2013717.<\/i><\/p><p>\u00a0<\/p><p><i>Es por ello que los coaches profesionales aprendemos <\/i><a href=\"https:\/\/cursos.gmotiva.com\/courses\/coaching\" target=\"_blank\" rel=\"noopener noreferrer\"><i>metodolog\u00edas y t\u00e9cnicas de coaching con fundamento<\/i><\/a><i> para llevar todo esto a la acci\u00f3n.<\/i><\/p><p>\u00a0<\/p><p><i>Hoy te regalamos un Ejercicio que puedes usar para tu vida personal, con clientes e incluso equipos.<\/i><\/p><p>\u00a0<\/p><p><i><strong>La escalera de logros.<\/strong><\/i><\/p><p>\u00a0<\/p><p>Con este ejercicio acompa\u00f1aremos a nuestros clientes o colaboradores a:<\/p><p>\u00a0<\/p><ul><li>Tener mayor claridad de pensamiento.<\/li><li>LLevar metas generales a pasos peque\u00f1os y manejables.<\/li><li>A facilitar experimentar logro en los primeros pasos peque\u00f1os que se vayan acumulando para generar persistencia en la consecusi\u00f3n de los pr\u00f3ximos pasos.<\/li><\/ul><p>Nuestro cliente llega con esta meta:<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8e98b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8e98b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2140191\" data-id=\"2140191\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7250d01 elementor-widget elementor-widget-image\" data-id=\"7250d01\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/1-1024x1024.jpg\" class=\"attachment-large size-large wp-image-4518\" alt=\"herramientas de coaching\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/1-1024x1024.jpg 1024w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/1-300x300.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/1-150x150.jpg 150w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/1-768x768.jpg 768w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/1.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e22e23a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e22e23a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-698586c\" data-id=\"698586c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acd27e1 elementor-widget elementor-widget-text-editor\" data-id=\"acd27e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ahora comienza nuestra intervenci\u00f3n.<\/p><p>\u00a0<\/p><p>Invitamos a que la persona o equipo piense en una l\u00ednea de tiempo de la consecuci\u00f3n de ese objetivo hacia atr\u00e1s.\u00a0<\/p><p>\u00a0<\/p><p>Es decir lo llevamos en primer lugar al futuro donde ya ha logrado la meta.\u00a0<\/p><p>\u00a0<\/p><p>Usando el ejemplo del carro&#8230; \u00bfQu\u00e9 ha tenido que suceder antes de tener la llave en mano? intentando definir el paso anterior, no 3 pasos m\u00e1s atr\u00e1s.<\/p><p>\u00a0<\/p><p>El cliente podr\u00eda responder: \u00abhaber pagado el carro\u00bb<\/p><p>\u00a0<\/p><p>Coach \/ Mentor: \u00bfY antes de eso?<\/p><p>\u00a0<\/p><p>Cliente: \u00abhaber ahorrado dinero\u00bb<\/p><p>\u00a0<\/p><p>Y con el dibujo en mano, o un formato impreso que tienes para el cliente de una escalera, le invitas que vaya escribiendo los hitos de la l\u00ednea de tiempo m\u00e1s esenciales.<\/p><p>\u00a0<\/p><p>As\u00ed el cliente podr\u00eda teminar este acompa\u00f1amiento con algo similar a:<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ea39f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ea39f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbea3be\" data-id=\"cbea3be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51ed352 elementor-widget elementor-widget-image\" data-id=\"51ed352\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/2-1024x1024.jpg\" class=\"attachment-large size-large wp-image-4519\" alt=\"libro herramientas de coaching\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/2-1024x1024.jpg 1024w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/2-300x300.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/2-150x150.jpg 150w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/2-768x768.jpg 768w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2024\/01\/2.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2909137 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2909137\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ee1595\" data-id=\"8ee1595\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbb2c58 elementor-widget elementor-widget-text-editor\" data-id=\"dbb2c58\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al haber definido cual es el peque\u00f1o y primer paso a ejecutar estamalos logrando su claridad de pensamiento, lo ve m\u00e1s posible y alcanzable, y esta es mi experiencia:<\/p><p>\u00a0<\/p><p>Efecta adem\u00e1s el compromiso con la ejecuci\u00f3n.<\/p><p>\u00a0<\/p><p>Al enfocarnos de una quincena a la otra en el primer paso esto se hace m\u00e1s manejable.<\/p><p>\u00a0<\/p><p>Por supuesto esto debe quedar en un plan de acci\u00f3n al final de la sesi\u00f3n de coaching, sino no sabes c\u00f3mo hacer un plan de acci\u00f3n profesional junto al cliente o equipo por favor invierte en <a href=\"https:\/\/cursos.gmotiva.com\/courses\/certificacion-coaching-ejecutivo-equipos\" target=\"_blank\" rel=\"noopener noreferrer\">nuestra certificaci\u00f3n online de coaching ejecutivo y de equipos.<\/a><\/p><p>\u00a0<\/p><p>El tama\u00f1o de la escalera puede variar y yo tambi\u00e9n le pido al cliente uno o dos hitos que lleven una celebrac\u00f3n al llegar ah\u00ed.<\/p><p>\u00a0<\/p><p>!S\u00ed! con estas herramientas t\u00fa puedes ayudar a otros a generar resultados cuando cuentas con la informaci\u00f3n y t\u00e9cnicas adecuadas.<\/p><p>\u00a0<\/p><p>Ahora te invito a conocer nuestra aula virtual con:<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ade5d48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ade5d48\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-696399d\" data-id=\"696399d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbd3d69 elementor-widget elementor-widget-heading\" data-id=\"cbd3d69\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">50 t\u00e9cnicas y Herramientas de Coaching Explicadas en Video.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26f7c7e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26f7c7e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-447a28f\" data-id=\"447a28f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e5c49d elementor-widget elementor-widget-video\" data-id=\"0e5c49d\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/STJYQK4rMvQ?si=7ctNXrmgSyKwtaYr&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a591be2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a591be2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c198dbb\" data-id=\"c198dbb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eee0991 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"eee0991\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.paypal.com\/cgi-bin\/webscr?cmd=_s-xclick&#038;hosted_button_id=5T5SVRYCTQH34\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Acceder a las 50 herramientas aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00abQuiero bajar de peso\u00bb<\/p>\n<p>\u00abQuiero terminar mis estudios\u00bb<\/p>\n<p>\u00abQuiero certificarme como coach\u00bb<\/p>\n<p>\u00abQuiero invertir mis ahorros\u00bb<\/p>\n<p>Etc.<\/p>\n<p>Son metas que no te van a mover a la acci\u00f3n, sabes \u00bfPorqu\u00e9? Porque la mente requiere claridad de pensamiento para facilitar la ejecuci\u00f3n.<\/p>\n<p>Por ejemplo ya sabemos que las metras generales no funcionan, funcionan mejor las espec\u00edficas, la que tienen una dificultad moderada y las que son manejables para nuestra mente.<\/p>\n","protected":false},"author":2,"featured_media":4519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[],"class_list":["entry","author-eduardo","has-excerpt","post-4516","post","type-post","status-publish","format-standard","has-post-thumbnail","category-coaching"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/4516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=4516"}],"version-history":[{"count":7,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/4516\/revisions"}],"predecessor-version":[{"id":4525,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/4516\/revisions\/4525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/4519"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=4516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=4516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=4516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}