{"id":4397,"date":"2023-02-23T17:55:08","date_gmt":"2023-02-23T23:55:08","guid":{"rendered":"https:\/\/www.psicologialaboral.net\/articulos\/?p=4397"},"modified":"2023-02-23T18:00:27","modified_gmt":"2023-02-24T00:00:27","slug":"elementor-4397","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/4397\/elementor-4397\/","title":{"rendered":"\ud83d\ude44 \u00bfQu\u00e9 hacer si un colaborador o cliente se pone metas irreales en un proceso de coaching?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4397\" class=\"elementor elementor-4397\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0975d8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0975d8a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-623903f\" data-id=\"623903f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-310be0e elementor-widget elementor-widget-image\" data-id=\"310be0e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2023\/02\/Diseno-sin-titulo-1.jpg\" class=\"attachment-large size-large wp-image-4402\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2023\/02\/Diseno-sin-titulo-1.jpg 960w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2023\/02\/Diseno-sin-titulo-1-300x169.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2023\/02\/Diseno-sin-titulo-1-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-944594c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"944594c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2840548\" data-id=\"2840548\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb45bcf elementor-widget elementor-widget-text-editor\" data-id=\"cb45bcf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando alguien se embarca en un proceso de coaching, es com\u00fan que se establezcan metas y objetivos que se desean lograr durante el proceso. Estas metas pueden variar desde objetivos personales y profesionales hasta objetivos de desarrollo personal y emocional. El establecimiento de metas es una parte importante del proceso de coaching, ya que ayuda al coachee a enfocarse en lo que quiere lograr y a tomar medidas para alcanzarlo.<\/p><p>Sin embargo, en algunos casos, los coachees pueden establecer metas que son irreales o inalcanzables. Esto puede deberse a una falta de comprensi\u00f3n sobre lo que es posible o una falta de confianza en s\u00ed mismos. Si bien puede ser frustrante para el coachee cuando se da cuenta de que sus metas son irreales, es importante recordar que esto es parte del proceso de aprendizaje y crecimiento.\u00a0<\/p><p>\u00a0<\/p><p><strong><u>El mayor error que puedes cometer como l\u00edder coach o coach es decir:<\/u><\/strong><\/p><p>\u00a0<\/p><p><strong><u>Esa meta es irreal.<\/u><\/strong><\/p><p>\u00a0<\/p><p><strong><u>S\u00ed, porque eso viene de tu experiencia.<\/u><\/strong><\/p><p>\u00a0<\/p><p>Como coach, hay varias cosas que puedes hacer para ayudar a tu coachee si se encuentra en esta situaci\u00f3n.<\/p><p><strong>Explorar y analizar la meta:<\/strong> Es importante que como coach ayudes al coachee a reflexionar sobre la meta que ha establecido. Ayuda a identificar las razones detr\u00e1s de la meta y analizar su importancia y la viabilidad de alcanzarla. En algunos casos, puede haber un malentendido o falta de informaci\u00f3n que lleva al coachee a establecer una meta irreales. Ayuda a aclarar los detalles de la meta y los pasos necesarios para alcanzarla.<\/p><p><strong>Identificar limitaciones:<\/strong> Es importante que como coach ayudes al coachee a identificar sus fortalezas y debilidades, as\u00ed como los recursos y limitaciones a su alcance. Si se establece una meta que es claramente inalcanzable debido a las limitaciones del coachee, debes trabajar juntos para encontrar una meta m\u00e1s realista que sea m\u00e1s alcanzable.<\/p><p><strong>Ser realista:<\/strong> Como coach, es importante ser realista en cuanto a las metas que se establecen. Si la meta del coachee es claramente inalcanzable, es mejor que ayudes a establecer una meta que sea m\u00e1s realista y alcanzable. Esto no significa que no se deba establecer una meta ambiciosa, pero debe ser algo que el coachee tenga la capacidad y recursos para alcanzar.<\/p><p><strong>Desafiar y motivar:<\/strong> Si bien es importante ser realista, tambi\u00e9n es importante desafiar y motivar al coachee. Ayuda a establecer metas ambiciosas pero alcanzables, y trabaja con ellos para desarrollar un plan de acci\u00f3n que los ayude a alcanzar sus metas. Motiva al coachee a superar sus limitaciones y a trabajar en su desarrollo personal y profesional.<\/p><p><strong>Establecer hitos:<\/strong> Como coach, puedes ayudar al coachee a establecer hitos o metas m\u00e1s peque\u00f1as a lo largo del camino para alcanzar su objetivo final. Estos hitos pueden ser un recordatorio constante del progreso que se est\u00e1 haciendo y ayudar a mantener la motivaci\u00f3n del coachee.<\/p><p>En resumen, cuando un coachee establece metas irreales,<i> es importante trabajar juntos para analizar y comprender la meta, identificar limitaciones, establecer metas realistas, desafiar y motivar, y establecer hitos. A trav\u00e9s de este enfoque, el coachee puede seguir avanzando y lograr el \u00e9xito en su proceso de coaching.<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eca41d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eca41d2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e00c777\" data-id=\"e00c777\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-367191a elementor-widget elementor-widget-heading\" data-id=\"367191a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres convertirte en coach o l\u00edder Coach? aqu\u00ed est\u00e1 nuestra mejor opci\u00f3n:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-872ba52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"872ba52\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dd08c7\" data-id=\"9dd08c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c7b62e elementor-widget elementor-widget-image\" data-id=\"2c7b62e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cursos.gmotiva.com\/courses\/certificacion-coaching-ejecutivo-equipos\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2023\/02\/coaching-de-equipos-y-ejecutivo-certificacion-online.jpg\" class=\"attachment-large size-large wp-image-4376\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2023\/02\/coaching-de-equipos-y-ejecutivo-certificacion-online.jpg 600w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2023\/02\/coaching-de-equipos-y-ejecutivo-certificacion-online-300x169.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El mayor error que puedes cometer como l\u00edder coach o coach es decir:<\/p>\n<p>Esa meta es irreal.<\/p>\n<p>S\u00ed, porque eso viene de tu experiencia.<\/p>\n","protected":false},"author":2,"featured_media":4402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["entry","author-eduardo","has-excerpt","post-4397","post","type-post","status-publish","format-standard","has-post-thumbnail","category-motivacion-laboral-2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/4397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=4397"}],"version-history":[{"count":7,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/4397\/revisions"}],"predecessor-version":[{"id":4405,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/4397\/revisions\/4405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/4402"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=4397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=4397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=4397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}