{"id":2924,"date":"2018-06-06T18:04:30","date_gmt":"2018-06-07T00:04:30","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=2924"},"modified":"2021-02-08T17:58:26","modified_gmt":"2021-02-08T23:58:26","slug":"3-tips-para-organizarte-mejor-y-administrar-tu-tiempo","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/2924\/3-tips-para-organizarte-mejor-y-administrar-tu-tiempo\/","title":{"rendered":"3 tips para organizarte mejor y administrar tu tiempo."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2924\" class=\"elementor elementor-2924\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f6d13d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f6d13d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30d1578\" data-id=\"30d1578\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46078a4 elementor-widget elementor-widget-text-editor\" data-id=\"46078a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En un mundo tan competitivo parece que siempre tenemos menos tiempo, por lo tanto organizarse con mayor efectividad tiene un gran beneficio para nuestra vida, compartimos unas ideas pr\u00e1cticas del libro Organ\u00edzate con eficacia de David Allen (Getting things done) Que puede cambiar tu productividad.<\/p><h3>1. El cerebro no es para almacenar.<\/h3><p>Suponemos que nuestro cerebro es una gran bodega para almacenar, fechas, nombres, pendientes y que podemos acceder a estos datos cuando es necesario, sin embargo esta idea es falsa, nuestro cerebro est\u00e1 dise\u00f1ado para crear ideas y para adaptarse a las situaciones, no para almacenarlas.<\/p><p><strong>Nuestro cerebro no est\u00e1 dise\u00f1ado para recordar cada detalle de informaci\u00f3n<\/strong>, por m\u00e1s que hayamos estudiado muchas cosas en la escuela y el colegio actualmente no las recordamos, no porque nuestro cerebro tenga una incapacidad, sino que es su naturaleza, la cual no consiste en almacenar, al menos no es su funci\u00f3n primordial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0e5fa0 elementor-widget elementor-widget-image\" data-id=\"d0e5fa0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"242\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/06\/como-organizarse.jpg\" class=\"attachment-large size-large wp-image-2925\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/06\/como-organizarse.jpg 640w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/06\/como-organizarse-300x113.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9765f88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9765f88\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc0ec3f\" data-id=\"bc0ec3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f21793b elementor-widget elementor-widget-spacer\" data-id=\"f21793b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c3755e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c3755e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6700e87\" data-id=\"6700e87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f738e3b elementor-widget elementor-widget-image\" data-id=\"f738e3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-791x1024.jpg\" class=\"attachment-large size-large wp-image-3050\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-791x1024.jpg 791w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-232x300.jpg 232w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-768x994.jpg 768w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-081e50b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"081e50b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e6dab4\" data-id=\"8e6dab4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dca379 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4dca379\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa236a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa236a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c32e78e\" data-id=\"c32e78e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e87d63a elementor-widget elementor-widget-spacer\" data-id=\"e87d63a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6522156 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6522156\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc52d5b\" data-id=\"fc52d5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-969fac0 elementor-widget elementor-widget-text-editor\" data-id=\"969fac0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Estrategia<br \/><br \/><\/h3><p>Debes apoyarte en un sistema que te permita poder tener presente la informaci\u00f3n que te evite postergar o distraerte.<\/p><p>Actualmente hay m\u00e9todos de priorizaci\u00f3n e incluso apps para dispositivos que nos ayudan a organizar nuestras actividades, y que nos trajera al frente lo que es necesario recordar.<\/p><h3>2. Tener una mente enfocada.<\/h3><p>El caso contrario es tener enfrente de nosotros tantas distracciones que en cualquier momento determinado atrapen nuestro atenci\u00f3n.<\/p><p>Por ejemplo mientras realizas una tarea, tienes invisible otros pendientes te pueden llamar tu atenci\u00f3n, escuchas m\u00fasica que hace que tu pensamiento se vaya a otros lugares, sueles estar chequeando las redes sociales o las ofertas que te llegan al correo electr\u00f3nico, etc. Tiempo para terminar una tarea ser\u00e1 mucho mayor en lugar de que te comprometas a eliminar todos los distractores y poder tener tu atenci\u00f3n en tu tarea prioritaria.<\/p><p>Por lo tanto hacer m\u00faltiples cosas a la vez podr\u00eda jugar en contra de tu productividad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dae4112 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dae4112\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88b8c9d\" data-id=\"88b8c9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74bdfa0 elementor-widget elementor-widget-image\" data-id=\"74bdfa0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/06\/como-ser-organizado.jpg\" class=\"attachment-large size-large wp-image-2926\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/06\/como-ser-organizado.jpg 640w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/06\/como-ser-organizado-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc41089 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc41089\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28865c7\" data-id=\"28865c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b92a7f elementor-widget elementor-widget-text-editor\" data-id=\"5b92a7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>3. Tiempos dedicados.<\/h3><blockquote><p>Planificar horarios para actividades en donde te apegues a ello.<\/p><\/blockquote><p><br \/>Si estableces que lo prioritario en tu rutina cada d\u00eda es revisar tu email, ap\u00e9gate a ello por ejemplo de 8 a 10 am por ejemplo, dedica un espacio de distracci\u00f3n que sea espec\u00edfico para revisar redes sociales, el punto es que ellas no se mezclen si no que tengan un horario espec\u00edfico.<\/p><p>!Adelante ponlo en la pr\u00e1ctica! Ahora depende de usted, siempre ha dependido de usted y seguir\u00e1 dependiendo de usted.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dc4f66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dc4f66\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa64084\" data-id=\"aa64084\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3d84a2 elementor-widget elementor-widget-spacer\" data-id=\"c3d84a2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En un mundo tan competitivo parece que siempre tenemos menos tiempo, por lo tanto organizarse con mayor efectividad tiene un gran beneficio para nuestra vida, compartimos unas ideas pr\u00e1cticas del libro Organ\u00edzate con eficacia de David Allen (Getting things done) Que puede cambiar tu productividad. 1. El cerebro no es para almacenar. Suponemos que nuestro<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/2924\/3-tips-para-organizarte-mejor-y-administrar-tu-tiempo\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96,87,1,46,88],"tags":[],"class_list":["entry","author-eduardo","post-2924","post","type-post","status-publish","format-standard","has-post-thumbnail","category-coaching","category-liderazgo-y-motivacion","category-mandos-medios","category-motivacion-laboral-2","category-talento-humano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=2924"}],"version-history":[{"count":11,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2924\/revisions"}],"predecessor-version":[{"id":3855,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2924\/revisions\/3855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/2931"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=2924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=2924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=2924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}