{"id":2806,"date":"2017-10-11T16:16:08","date_gmt":"2017-10-11T22:16:08","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=2806"},"modified":"2021-02-08T18:01:57","modified_gmt":"2021-02-09T00:01:57","slug":"ejercicio-estrategico-que-cambio-mi-motivacion-y-exito-en-la-vida","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/2806\/ejercicio-estrategico-que-cambio-mi-motivacion-y-exito-en-la-vida\/","title":{"rendered":"Ejercicio estrat\u00e9gico que cambi\u00f3 mi motivaci\u00f3n y \u00e9xito en la vida."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2806\" class=\"elementor elementor-2806\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c25c240 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c25c240\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79daff19\" data-id=\"79daff19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3156f32e elementor-widget elementor-widget-text-editor\" data-id=\"3156f32e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2810\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/04\/motivacion-y-exito-1024x683.jpg\" alt=\"\" width=\"550\" height=\"367\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/04\/motivacion-y-exito-1024x683.jpg 1024w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/04\/motivacion-y-exito-300x200.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/04\/motivacion-y-exito-768x512.jpg 768w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/04\/motivacion-y-exito.jpg 1280w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/p><p>Quiero compartirle parte de lo que me ha funcionado para tener logros que me hacen feliz dando charlas y talleres en mi pa\u00eds.<\/p><p>He identificado que las personas que m\u00e1s compran mis <a href=\"http:\/\/www.psicologialaboral.net\/articulos\/descargas\/\"><strong>productos digitales de Psicolog\u00eda para el potencial humano<\/strong><\/a>, son personas que desean dar charlas, talleres y capacitaciones, tanto coaches, Recursos humanos, l\u00edderes y psic\u00f3logos que deben afrontar el reto de hacer de sus servicios algo din\u00e1mico que las personas amen y con los cuales vean resultados en la gente. Pues bien creo que ese es mi fuerte, \u00abmi estadio\u00bb y en donde est\u00e1n mis habilidades.<\/p><p>Cuando termin\u00e9 de graduarme como psic\u00f3logo yo sal\u00ed con una gran frustraci\u00f3n y era el saber de todo pero en la teor\u00eda, algunas personas se sent\u00edan c\u00f3modas as\u00ed, pero no era mi caso que ya entend\u00eda que para generar resultados debemos facilitar la puesta en pr\u00e1ctica del conocimiento, creo que una fortaleza m\u00eda es esa y es mi actual negocio.<\/p><p>Lo que deseo compartir con usted es mi fiel convicci\u00f3n de que:<\/p><blockquote><p>Cuando \u00abentras a un juego\u00bb donde tus habilidades son las apreciadas llevas las de ganar.<\/p><\/blockquote><p>D\u00e9jeme por favor traducir esto. Es probable que a este punto por todo lo que compartimos en Grupo Motiva usted sepa la importancia de identificar sus fortalezas predominantes; ahora por un instante suponga que las fortalezas predominantes suyas son:<\/p><p>&#8211; <a href=\"http:\/\/enriquecetupsicologia.com\/e-learning\/1395\/descargar-inteligencia-emocional-video-capacitacion\/\" target=\"_blank\" rel=\"noopener\"><strong>Inteligencia emocional<\/strong><\/a><br \/>&#8211; Inteligencia social.<br \/>&#8211; Generosidad.<br \/>&#8211; Amabilidad.<br \/>&#8211; Amor.<\/p><p>Propias de la virtud \u00abHumanidad\u00bb.<\/p><p>Adem\u00e1s suponga que su trabajo es estar frente a una computadora realizando reportes, informes, c\u00e1lculos y que el 80% de su trabajo se basa en la no interacci\u00f3n con las personas.<\/p><p><em>\u00bfLogra visualizar como es muy probable que usted sienta frustraci\u00f3n? \u00bflogra visualizar que muy probablemente no est\u00e1 aprovechando sus \u00abactivos\u00bb m\u00e1s valiosos? y que no s\u00f3lo ser\u00e1 una barrera para el \u00e9xito, sino para su motivaci\u00f3n a largo plazo.<\/em><\/p><p>Pues bien, a eso me refiero de \u00abestar jugando un partido\u00bb cuyas habilidades valiosas sean las que usted posee. Que tal si una persona con esas 5 fortalezas predominantes trabaja atendiendo clientes, ser\u00eda una maravilla tanto para su autorrealizaci\u00f3n, \u00e9xito y motivaci\u00f3n a largo plazo, pero tambi\u00e9n para sus compa\u00f1eros y clientes.<\/p><p>Mi tesis final de graduaci\u00f3n la realic\u00e9 sobre <a href=\"http:\/\/enriquecetupsicologia.com\/e-learning\/15\/motivacion-laboral-sin-depender-del-dinero-2\/\" target=\"_blank\" rel=\"noopener\"><strong>motivaci\u00f3n laboral<\/strong><\/a> y una de las principales conclusiones es que el \u00abfactor desmotivaci\u00f3n\u00bb de mayor impacto, es no tener un trabajo con caracter\u00edsticas que le permitan desarrollar su potencial.<\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7754e6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7754e6b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e3ccea\" data-id=\"0e3ccea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-922fa7d elementor-widget elementor-widget-image\" data-id=\"922fa7d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-724x1024.jpg\" class=\"attachment-large size-large wp-image-3026\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-724x1024.jpg 724w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-212x300.jpg 212w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-768x1086.jpg 768w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2489694 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2489694\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2386be\" data-id=\"c2386be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f72d9d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0f72d9d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-85bebed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"85bebed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c73f83\" data-id=\"7c73f83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbcde66 elementor-widget elementor-widget-spacer\" data-id=\"cbcde66\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7f9713 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7f9713\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c073f1\" data-id=\"0c073f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec4c624 elementor-widget elementor-widget-text-editor\" data-id=\"ec4c624\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>\u00bfQu\u00e9 pasa si su actual trabajo no coincide del todo con sus fortalezas y habilidades?<\/h2><p>!No caiga en p\u00e1nico! puede iniciar un proceso de negociaci\u00f3n con su jefe de alg\u00fan nuevo proyecto donde est\u00e9n impl\u00edcitas sus principales fortalezas, puede dentro de su misma autoridad involucrarse en tareas afines. Pero lo primero por supuesto es saber cu\u00e1les son sus fortalezas predominantes, vamos a las parte pr\u00e1ctica:<\/p><p>A. Realizando los test de\u00a0<a href=\"https:\/\/www.authentichappiness.sas.upenn.edu\/es\/testcenter\" target=\"_blank\" rel=\"noopener\">VIA fortalezas personales<\/a>\u00a0recomendados, escriba a continuaci\u00f3n sus 5 fortalezas predominantes.<\/p><p>1.<br \/>2.<br \/>3.<br \/>4.<br \/>5.<\/p><p>Aqu\u00ed viene su trabajo.<\/p><p>B. Piense en cu\u00e1l\u00a0trabajo ser\u00eda el m\u00e1s ideal seg\u00fan esas 5 fortalezas (aunque no\u00a0sea el actual).<\/p><p>C. Identifique las tareas que se deben realizar en ese \u00abtrabajo ideal\u00bb.<\/p><p>D. Por \u00faltimo (solamente si ha realizado los pasos anteriores encontrar\u00e1 coincidencias), identifique cu\u00e1les de esas tareas pueden ser un proyecto en su trabajo actual.<\/p><h2>Ejemplo.<\/h2><p>Tomando en consideraci\u00f3n las 5 fortalezas de nuestro ejemplo, aunque usted no trabaje en servicio al cliente, puede proponer un proyecto donde sea usted quien deba presentar ante otras personas los resultados de esos informes. Puede usted proponerse para liderar las actividades sociales, podr\u00eda complementar sus estudios con un curso y ofrecerse como mediador (a) de conflictos, ser usted quien haga los reconocimientos p\u00fablicos, etc.<\/p><blockquote><p>Le garantizo que realizar este ejercicio con la suficiente paciencia para ir paso por paso puede ser uno de los ejercicios m\u00e1s estrat\u00e9gicos y reveladores de su vida.<\/p><\/blockquote><p><em>Advertencia: Requiere trabajo encontrar esas coincidencias en su trabajo (m\u00e1s en algunos casos que otros) si es que no las identifica r\u00e1pidamente, el principal punto es que sea muy sincero, ya que muchas veces nuestro mismo orgullo no nos deja ver que hay oportunidades de mejora.<\/em><\/p><p>Las otras alternativas m\u00e1s profundas para \u00abinvolucrarse en juego que aprecie nuestras habilidades\u00bb son las rotaciones de tareas, las rotaciones de puestos y un \u00faltimo caso, el cambio de trabajo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26b3ba5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26b3ba5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b518a6e\" data-id=\"b518a6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e72032e elementor-widget elementor-widget-spacer\" data-id=\"e72032e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Quiero compartirle parte de lo que me ha funcionado para tener logros que me hacen feliz dando charlas y talleres en mi pa\u00eds. He identificado que las personas que m\u00e1s compran mis productos digitales de Psicolog\u00eda para el potencial humano, son personas que desean dar charlas, talleres y capacitaciones, tanto coaches, Recursos humanos, l\u00edderes y<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/2806\/ejercicio-estrategico-que-cambio-mi-motivacion-y-exito-en-la-vida\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,74,91,46,70,88],"tags":[],"class_list":["entry","author-eduardo","post-2806","post","type-post","status-publish","format-standard","has-post-thumbnail","category-administracion-del-talento-humano-2","category-capacitaciones-costa-rica","category-dinamicas-grupales","category-motivacion-laboral-2","category-psicologia-organizacional-positiva","category-talento-humano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=2806"}],"version-history":[{"count":14,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2806\/revisions"}],"predecessor-version":[{"id":3870,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2806\/revisions\/3870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/2810"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=2806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=2806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}