{"id":2712,"date":"2017-05-01T13:08:51","date_gmt":"2017-05-01T19:08:51","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=2712"},"modified":"2021-02-08T18:27:56","modified_gmt":"2021-02-09T00:27:56","slug":"personalidad-influyente-principios-y-estrategias","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/2712\/personalidad-influyente-principios-y-estrategias\/","title":{"rendered":"Personalidad influyente (Principios y estrategias)."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2712\" class=\"elementor elementor-2712\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58b829e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58b829e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3aaa868c\" data-id=\"3aaa868c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e8fabd0 elementor-widget elementor-widget-text-editor\" data-id=\"6e8fabd0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><\/div><p>Hay un excelente trabajo hecho por Robert B. Cialdini el cual concluye determinados principios que si aplicas te conviertes en persona influyente, ya sea como l\u00edder, como padre, como vendedor, etc.<\/p><p>Recordemos que muchas veces requerimos ser influyentes para convencer a otros, para que adopten ideas y compromisos, o para venderles un producto o servicio.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2713\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/01\/influencia-Robert-B.-Cialdini-1024x795.jpg\" alt=\"\" width=\"462\" height=\"358\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/01\/influencia-Robert-B.-Cialdini-1024x795.jpg 1024w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/01\/influencia-Robert-B.-Cialdini-300x233.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/01\/influencia-Robert-B.-Cialdini-768x596.jpg 768w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2017\/01\/influencia-Robert-B.-Cialdini.jpg 1920w\" sizes=\"(max-width: 462px) 100vw, 462px\" \/><\/p><h2>El principio de la reciprocidad\u00a0(Robert B. Cialdini).<\/h2><p>El primer principio de la reciprocidad lo que dice es que cuando t\u00fa das algo existe en la otra persona como esa necesidad de responder a ello.<\/p><p>Por ejemplo cuando un mesero entrega un confite al final de haber atendido, las propina aumentan, pero si da dos confites y la forma en que lo hace es personalizado; las propinas llegan:<\/p><div><\/div><div><blockquote><p>a incrementarse hasta en un 23% aproximadamente.<\/p><\/blockquote><\/div><p>Imagine un mesero entreg\u00e1ndole unos confites al final y expresando el gusto de que usted haya venido y lo hace recordando su nombre.<\/p><p><em><strong>Que es un aspecto psicol\u00f3gico intentar devolver la amabilidad.<\/strong><\/em><\/p><p>Otro ejemplo de reciprocidad que se da en los supermercados cuando te entregan una prueba de comida gratis, eso hace que por lo menos gastes unos pocos minutos escuch\u00e1ndole e incrementa la posibilidad de venta.<\/p><h2>La estrategia psicol\u00f3gica de reciprocidad.<\/h2><p>Cuando requiera una acci\u00f3n determinada de las otras personas, empiece usted por dar una acci\u00f3n en el sentido que despierten la reciprocidad en lo que usted busca.<\/p><p>En lo que es la influencia de un l\u00edder esto se nota cuando el l\u00edder debe pedirle compromiso las personas, las que mejor responder\u00e1n son aquellas que generalmente han recibido el compromiso de su l\u00edder.<\/p><p>Los padres que tienen la capacidad de sincerarse con sus hijos, son aquellos que generalmente reciben mayor sinceridad de ellos.<\/p><p>Recordemos que este principio de reciprocidad no aplica s\u00f3lo para cosas materiales, si no para tambi\u00e9n cosas intangibles, por mencionar algunas de ellas amabilidad, apertura, confianza, flexibilidad, respeto.<\/p><p>Al rato que usted tiene ahora es pensar en el principio de reciprocidad personalizado a lo que usted requiere influenciar. <em><strong>S\u00f3lo recuerde que sus probabilidades aumentar\u00e1n cuando usted haya sido el primero en dar.<\/strong><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1238bf9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1238bf9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62b8bb5\" data-id=\"62b8bb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c4f507 elementor-widget elementor-widget-image\" data-id=\"4c4f507\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-791x1024.jpg\" class=\"attachment-large size-large wp-image-3050\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-791x1024.jpg 791w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-232x300.jpg 232w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-gratis-rrhh2-VIP-768x994.jpg 768w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29b7c0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29b7c0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ca9744\" data-id=\"0ca9744\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b57fdd2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b57fdd2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e9e66b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e9e66b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76ca8d3\" data-id=\"76ca8d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcf227e elementor-widget elementor-widget-spacer\" data-id=\"dcf227e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hay un excelente trabajo hecho por Robert B. Cialdini el cual concluye determinados principios que si aplicas te conviertes en persona influyente, ya sea como l\u00edder, como padre, como vendedor, etc. Recordemos que muchas veces requerimos ser influyentes para convencer a otros, para que adopten ideas y compromisos, o para venderles un producto o servicio.<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/2712\/personalidad-influyente-principios-y-estrategias\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,87],"tags":[84],"class_list":["entry","author-eduardo","post-2712","post","type-post","status-publish","format-standard","has-post-thumbnail","category-administracion-del-talento-humano-2","category-liderazgo-y-motivacion","tag-liderazgo"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=2712"}],"version-history":[{"count":12,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2712\/revisions"}],"predecessor-version":[{"id":3882,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2712\/revisions\/3882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/2713"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=2712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=2712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=2712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}