{"id":2583,"date":"2016-02-02T15:55:51","date_gmt":"2016-02-02T21:55:51","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=2583"},"modified":"2021-02-08T18:34:44","modified_gmt":"2021-02-09T00:34:44","slug":"dinamica-para-crear-integracion-y-trabajo-en-equipo-en-la-empresa","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/2583\/dinamica-para-crear-integracion-y-trabajo-en-equipo-en-la-empresa\/","title":{"rendered":"Din\u00e1mica para crear integraci\u00f3n y trabajo en equipo en la empresa."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2583\" class=\"elementor elementor-2583\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41b48386 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41b48386\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e6360d8\" data-id=\"6e6360d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16b6d15c elementor-widget elementor-widget-text-editor\" data-id=\"16b6d15c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/dinamicas-de-trabajo-en-equipo-empresa.jpg\" rel=\"attachment wp-att-2584\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2584\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/dinamicas-de-trabajo-en-equipo-empresa.jpg\" alt=\"dinamicas de trabajo en equipo empresa\" width=\"440\" height=\"284\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/dinamicas-de-trabajo-en-equipo-empresa.jpg 960w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/dinamicas-de-trabajo-en-equipo-empresa-300x193.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/dinamicas-de-trabajo-en-equipo-empresa-768x495.jpg 768w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/dinamicas-de-trabajo-en-equipo-empresa-170x110.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/dinamicas-de-trabajo-en-equipo-empresa-284x183.jpg 284w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/p><p style=\"text-align: justify;\"><strong>\u00bfConoce usted esas bolas de lana que siempre salen al lado de un gato en las fotos?<\/strong><\/p><p style=\"text-align: justify;\">Bien con una as\u00ed le pedimos a la gente que se pongan en c\u00edrculo y comenzamos con un integrante que\u00a0comenzar\u00e1 a hablar sobre qui\u00e9n es, sus gustos, sue\u00f1os, etc. cuando otra persona le \u201cresuene\u201d ; es decir, tambi\u00e9n tenga ese gusto alzar\u00e1 la mano y la persona que tiene la bola de lana la pasar\u00e1 a alguna de ellas y as\u00ed consecutivamente hasta terminar con la \u00faltima persona en el c\u00edrculo. Los comentarios posteriores los realizo centrado en que siempre en un equipo hay buenas y malas, pero cuando nos acercamos un poco m\u00e1s, conocemos a la otra persona y sobre toda hacemos un esfuerzo por ver lo positivo en el otro aunque no estemos de acuerdo con sus ideas, esto mantiene al equipo unido.<\/p><p style=\"text-align: justify;\">Es una actividad que a primera instancia me parec\u00eda \u201ccursi\u201d pero que s\u00f3lo atrevi\u00e9ndose aplicarla vemos los resultados.<\/p><p style=\"text-align: justify;\"><em><span style=\"text-decoration: underline;\">La teor\u00eda cient\u00edfica (Hot Spots: Why Some Teams, Workplaces, and Organizations Buzz with Energy &#8211; And Others Don&#8217;t<br \/>by Lynda Gratton) indica que los equipos de trabajo m\u00e1s productivos son aquellos cuyos integrantes colaboran entre s\u00ed<\/span><\/em>, y si profundizamos para que sus integrantes colaboren entre s\u00ed lo obtenemos m\u00e1s donde hay confianza, y es en las mismas diferencias laborales que van creando una desconfianza que los aleja de lo anterior, es por ello que trabajar el acercamiento de sus integrantes es importante, aqu\u00ed viene el secreto:<\/p><blockquote><p style=\"text-align: justify;\">Este acercamiento se puede trabajar mediante el permitirles conocerse m\u00e1s, que sepan quienes son incluso m\u00e1s all\u00e1 del compa\u00f1ero de trabajo, que logren visualizar que no son tan diferentes y que incluso podr\u00edan amar las mismas cosas, darle incluso adem\u00e1s motivos que le faciliten posteriormente entablar conversaciones, etc. esto es lo que logra esta actividad y hay otro secreto: hacerlo con un tema m\u00e1s personal que laboral para permitir la relajaci\u00f3n y disfrute de los participantes.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be498b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be498b7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b93d44\" data-id=\"7b93d44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f199a06 elementor-widget elementor-widget-image\" data-id=\"f199a06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"653\" height=\"758\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/07\/1d.jpg\" class=\"attachment-large size-large wp-image-2996\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/07\/1d.jpg 653w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/07\/1d-258x300.jpg 258w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-512bf8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"512bf8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24f0374\" data-id=\"24f0374\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c857277 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c857277\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cef4fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cef4fa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9358f31\" data-id=\"9358f31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-665e895 elementor-widget elementor-widget-spacer\" data-id=\"665e895\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfConoce usted esas bolas de lana que siempre salen al lado de un gato en las fotos? Bien con una as\u00ed le pedimos a la gente que se pongan en c\u00edrculo y comenzamos con un integrante que\u00a0comenzar\u00e1 a hablar sobre qui\u00e9n es, sus gustos, sue\u00f1os, etc. cuando otra persona le \u201cresuene\u201d ; es decir, tambi\u00e9n<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/2583\/dinamica-para-crear-integracion-y-trabajo-en-equipo-en-la-empresa\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,50,74,63,96],"tags":[],"class_list":["entry","author-eduardo","post-2583","post","type-post","status-publish","format-standard","has-post-thumbnail","category-administracion-del-talento-humano-2","category-capacitacion-recursos-humanos-2","category-capacitaciones-costa-rica","category-clima-organizacional","category-coaching"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=2583"}],"version-history":[{"count":10,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2583\/revisions"}],"predecessor-version":[{"id":3915,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2583\/revisions\/3915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/2584"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=2583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=2583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=2583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}