{"id":2564,"date":"2016-05-01T12:54:08","date_gmt":"2016-05-01T18:54:08","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=2564"},"modified":"2021-02-08T18:33:14","modified_gmt":"2021-02-09T00:33:14","slug":"historia-de-superacion-el-rey-sin-dientes","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/2564\/historia-de-superacion-el-rey-sin-dientes\/","title":{"rendered":"Historia de superaci\u00f3n: El Rey sin dientes."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2564\" class=\"elementor elementor-2564\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dfc21a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dfc21a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77890be\" data-id=\"77890be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24670337 elementor-widget elementor-widget-text-editor\" data-id=\"24670337\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2565\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/El-rey-sin-dientes.jpg\" alt=\"El rey sin dientes\" width=\"450\" height=\"300\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/El-rey-sin-dientes.jpg 960w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/El-rey-sin-dientes-300x200.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/El-rey-sin-dientes-768x512.jpg 768w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/El-rey-sin-dientes-170x113.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/El-rey-sin-dientes-284x189.jpg 284w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2016\/01\/El-rey-sin-dientes-135x90.jpg 135w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div><div><\/div><p style=\"text-align: justify;\">Existen muchas historias que intentan dejar un mensaje de aprendizaje o motivador, <strong>pero pocas lo logran.<\/strong><\/p><p style=\"text-align: justify;\">Hoy hemos seleccionado una que esperamos le guste y que pueda utilizar incluso para contarla a otros, ya que se presta mucho para enriquecer diversos temas en las relaciones interpersonales y <span style=\"text-decoration: underline;\"><em><strong>la importancia del lenguaje no verbal, la forma de decir las cosas y c\u00f3mo mediante esta habilidad logramos mucho m\u00e1s con las personas.<\/strong><\/em><\/span><\/p><h2 style=\"text-align: justify;\">El rey sin dientes.<\/h2><p style=\"text-align: justify;\">Una sabia y conocida an\u00e9cdota \u00e1rabe dice que en una ocasi\u00f3n, un Sult\u00e1n so\u00f1\u00f3 que hab\u00eda perdido todos los dientes. Despu\u00e9s de despertar, mand\u00f3 a llamar a un adivino para que interpretase su sue\u00f1o.<\/p><p style=\"text-align: justify;\">\u201c\u00a1Qu\u00e9 desgracia, mi Se\u00f1or!\u201d exclam\u00f3 el adivino, \u201ccada diente ca\u00eddo representa la p\u00e9rdida de un pariente de vuestra Majestad.\u201d<\/p><p style=\"text-align: justify;\">\u201c\u00a1Qu\u00e9 insolencia!\u201d grit\u00f3 el Sult\u00e1n enfurecido, \u201c\u00bfC\u00f3mo te atreves a decirme semejante cosa? \u00a1Fuera de aqu\u00ed!\u201d Llam\u00f3 a su guardia y orden\u00f3 que le dieran cien latigazos.<\/p><p style=\"text-align: justify;\">M\u00e1s tarde orden\u00f3 que le trajesen a otro adivino y le cont\u00f3 lo que hab\u00eda so\u00f1ado. \u00c9ste, despu\u00e9s de escuchar al Sult\u00e1n con atenci\u00f3n, le dijo: \u201c\u00a1Excelso Se\u00f1or! Gran felicidad os ha sido reservada\u2026 \u00a1El sue\u00f1o significa que sobrevivir\u00e9is a todos vuestros parientes!\u201d<\/p><p style=\"text-align: justify;\">Se ilumin\u00f3 el semblante del Sult\u00e1n con una gran sonrisa y orden\u00f3 le dieran cien monedas de oro.<\/p><p style=\"text-align: justify;\">Cuando \u00e9ste sal\u00eda del palacio, uno de los cortesanos le dijo admirado: \u201cNo es posible! La interpretaci\u00f3n que hab\u00e9is hecho de los sue\u00f1os es la misma que la del primer adivino. No entiendo porque al primero le pag\u00f3 con cien latigazos y a ti con cien monedas de oro.<\/p><p style=\"text-align: justify;\">\u201cRecuerda bien, amigo m\u00edo,\u201d respondi\u00f3 el segundo adivino, \u201cque todo depende de la forma en el decir\u2026 uno de los grandes desaf\u00edos de la humanidad es aprender el arte de comunicarse.\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc374ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc374ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79fee64\" data-id=\"79fee64\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-134d1b6 elementor-widget elementor-widget-image\" data-id=\"134d1b6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-724x1024.jpg\" class=\"attachment-large size-large wp-image-3062\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-724x1024.jpg 724w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-212x300.jpg 212w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-768x1086.jpg 768w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c888c67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c888c67\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-abef970\" data-id=\"abef970\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6a0098 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a6a0098\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-198ec3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"198ec3e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b78c2d\" data-id=\"3b78c2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac38f5 elementor-widget elementor-widget-spacer\" data-id=\"8ac38f5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Existen muchas historias que intentan dejar un mensaje de aprendizaje o motivador, pero pocas lo logran. Hoy hemos seleccionado una que esperamos le guste y que pueda utilizar incluso para contarla a otros, ya que se presta mucho para enriquecer diversos temas en las relaciones interpersonales y la importancia del lenguaje no verbal, la forma<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/2564\/historia-de-superacion-el-rey-sin-dientes\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,62,83,1],"tags":[],"class_list":["entry","author-eduardo","post-2564","post","type-post","status-publish","format-standard","has-post-thumbnail","category-capacitacion-recursos-humanos-2","category-comunicacion-organizacional-2","category-inteligencia-emocional","category-mandos-medios"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=2564"}],"version-history":[{"count":16,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2564\/revisions"}],"predecessor-version":[{"id":3906,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2564\/revisions\/3906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/2565"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=2564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=2564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=2564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}