{"id":2208,"date":"2013-09-07T20:03:33","date_gmt":"2013-09-08T02:03:33","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=2208"},"modified":"2019-02-27T18:18:07","modified_gmt":"2019-02-28T00:18:07","slug":"curso-liderazgo-costa-rica","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/2208\/curso-liderazgo-costa-rica\/","title":{"rendered":"Curso liderazgo Costa Rica"},"content":{"rendered":"<h4 style=\"text-align: center;\">Curso taller de liderazgo Costa Rica<\/h4>\n<h4 style=\"text-align: center;\">Desarrollo de habilidades de liderazgo: L\u00edderes con influencia positiva e inteligencia emocional.<\/h4>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-costa-rica.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter  wp-image-2213\" alt=\"liderazgo costa rica\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-costa-rica.jpg\" width=\"540\" height=\"149\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-costa-rica.jpg 900w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-costa-rica-300x82.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-costa-rica-170x46.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-costa-rica-284x78.jpg 284w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<h3 style=\"text-align: justify;\">Justificaci\u00f3n e importancia de nuestro curso-taller de liderazgo.<\/h3>\n<p style=\"text-align: justify;\">Generar resultados sobresalientes con las personas&nbsp; no se alcanza desde una posici\u00f3n (ser el jefe, el supervisor, el encargado, etc.), sino desde el nivel de <b>influencia<\/b> positiva con las personas.<\/p>\n<p style=\"text-align: justify;\">Encontramos jefes y supervisores que lidian directamente con las personas y recurren a medios tales como el castigo, la amezana o las sanciones para comprometer o solucionar conflictos, lamentablemente esto <b>no ha dado resultado<\/b> y se vuelve contraproducente para ganar compromiso y conexi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Las habilidades requeridas para trabajar con las personas, su actitud, su motivaci\u00f3n, su esfuerzo no est\u00e1n dadas con un t\u00edtulo profesional por lo que hay una necesidad evidente de desarrollar habilidades de liderazgo e influencia.<\/p>\n<p style=\"text-align: justify;\"><i>La escucha asertiva, la soluci\u00f3n de conflictos sin resentimientos, el reconocer el esfuerzo de los dem\u00e1s, el correcto establecimiento de objetivos e incluso el uso adecuado de la palabra<\/i> son esenciales para las personas que necesitan del apoyo de los dem\u00e1s para generar resultados permanentes.<\/p>\n<h3 style=\"text-align: justify;\">Objetivo Curso Taller Liderazgo.<\/h3>\n<p style=\"text-align: justify;\"><b><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/Curso-de-liderazgo-en-costa-rica.jpg\"><img decoding=\"async\" class=\"alignleft  wp-image-2209\" alt=\"Curso de liderazgo en costa rica\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/Curso-de-liderazgo-en-costa-rica-300x188.jpg\" width=\"210\" height=\"132\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/Curso-de-liderazgo-en-costa-rica-300x188.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/Curso-de-liderazgo-en-costa-rica-170x106.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/Curso-de-liderazgo-en-costa-rica-284x178.jpg 284w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/Curso-de-liderazgo-en-costa-rica.jpg 491w\" sizes=\"(max-width: 210px) 100vw, 210px\" \/><\/a>Brindar t\u00e9cnicas y practicar habilidades para generar<\/b> conexi\u00f3n y compromiso con sus colaboradores.<\/p>\n<p style=\"text-align: justify;\">Ense\u00f1ar a los participantes la creaci\u00f3n de circunstancias <i>(La forma en c\u00f3mo se discute, da instrucciones, establece metas, intenta motivar y generar cambios, etc.) <\/i><span style=\"text-decoration: underline;\">en lugar<\/span> de entrar en problemas con las personas.<\/p>\n<p style=\"text-align: justify;\">&nbsp;Realizar escenificaciones de circuntsnacias con las que el l\u00edder se enfrenta e incorporar en el momento las t\u00e9cnicas y estrategias para un aprendizaje m\u00e1s pr\u00e1ctico y profundo.<\/p>\n<h3 style=\"text-align: justify;\">Temas de nuestro curso-taller de liderazgo.<\/h3>\n<p style=\"text-align: justify;\">&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <b>Liderazgo.<\/b><\/p>\n<p style=\"text-align: justify;\">&nbsp;\u00bfQu\u00e9 es ser l\u00edder?: Conceptos b\u00e1sicos del liderazgo.<\/p>\n<p style=\"text-align: justify;\">3 competencias indispensables:<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Trabajo en equipo:<\/span> Elementos facilitadores y c\u00f3mo implementarlos en el d\u00eda a d\u00eda.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">Administraci\u00f3n del tiempo:<\/span>&nbsp;Principios b\u00e1sicos para eliminar distracciones y generar resultados en lo prioritario.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">El canal de flujo:<\/span> C\u00f3mo generar mayor compromiso en las personas sin necesidad de castigos, sanciones o amenazas.<\/p>\n<p style=\"text-align: justify;\">&nbsp;&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <b>Establecimiento de metas.<\/b><\/p>\n<p style=\"text-align: justify;\">&nbsp;<a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945.jpg\"><img decoding=\"async\" class=\"alignleft  wp-image-2210\" alt=\"charla de liderazgo\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945-300x300.jpg\" width=\"180\" height=\"180\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945-300x300.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945-150x150.jpg 150w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945-1024x1024.jpg 1024w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945-32x32.jpg 32w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945-170x170.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945-284x284.jpg 284w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/canstockphoto11383945.jpg 1600w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a>Todo l\u00edder debe dar instrucciones y \u00f3rdenes de metas y objeticos para cumplir; sin embargo, una gran mayor\u00eda <span style=\"text-decoration: underline;\">no encuentra<\/span> las formas de comprometer a sus colaboradores, m\u00e1s a\u00fan cuando las tareas son repetitivas.<\/p>\n<p style=\"text-align: justify;\">&nbsp;Actividad l\u00fadica.<\/p>\n<p style=\"text-align: justify;\">&nbsp;Mediante esta actividad y un ejercicio se descubren los elementos indispensables del establecimiento de objetivos, sin ellos las personas no encontrar\u00e1n motivos interesantes, con ellos est\u00e1n m\u00e1s motivados en el logro del resultado.<\/p>\n<p style=\"text-align: justify;\">&nbsp;&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <b>Escucha asertiva &amp; soluci\u00f3n de conflictos.<\/b><\/p>\n<p style=\"text-align: justify;\"><b>&nbsp;<a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/seminario-liderazgo-costa-rica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-2211\" alt=\"seminario liderazgo costa rica\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/seminario-liderazgo-costa-rica-300x200.jpg\" width=\"189\" height=\"126\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/seminario-liderazgo-costa-rica-300x200.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/seminario-liderazgo-costa-rica-170x113.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/seminario-liderazgo-costa-rica-284x189.jpg 284w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/seminario-liderazgo-costa-rica-135x90.jpg 135w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/seminario-liderazgo-costa-rica.jpg 640w\" sizes=\"(max-width: 189px) 100vw, 189px\" \/><\/a><\/b>Cuando cada quien lleva sus razones y son expuestas pensamos en \u201cganarle\u201d al otro, lo cierto es que con ello no ganamos voluntad y compromiso. Cuando vamos con el fin de encontrar algo mejor que \u201csu raz\u00f3n\u201d y \u201cmi raz\u00f3n\u201d, trascendemos a \u201cnuestra raz\u00f3n\u201d.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><em>&nbsp;Escenificaci\u00f3n de 6 t\u00e9cnicas efectivas.<\/em><\/span><\/p>\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <b>Motivaci\u00f3n de los colaboradores..<\/b><\/p>\n<p><b><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-y-lideres-costa-rica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-2219\" alt=\"liderazgo y lideres costa rica\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-y-lideres-costa-rica-300x199.jpg\" width=\"210\" height=\"139\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-y-lideres-costa-rica-300x199.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-y-lideres-costa-rica-170x113.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-y-lideres-costa-rica-284x189.jpg 284w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-y-lideres-costa-rica-135x90.jpg 135w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/liderazgo-y-lideres-costa-rica.jpg 640w\" sizes=\"(max-width: 210px) 100vw, 210px\" \/><\/a>&nbsp;<\/b>Importancia de la motivaci\u00f3n en el desempe\u00f1o laboral, diferencias entre motivar \u201cdesde afuera\u201d a motivar \u201cdesde adentro\u201d, Encuesta de satisfacci\u00f3n laboral de f\u00e1cil aplicaci\u00f3n, el reconocimiento y las recomensas, t\u00e9cnicas y estrategias de aplicaci\u00f3n sin depender del dinero.<\/p>\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <b>Generando cambios.<\/b><\/p>\n<p><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/lideres-costa-rica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-2212\" alt=\"lideres costa rica\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/lideres-costa-rica.jpg\" width=\"137\" height=\"137\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/lideres-costa-rica.jpg 285w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/lideres-costa-rica-150x150.jpg 150w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/lideres-costa-rica-32x32.jpg 32w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/lideres-costa-rica-170x170.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/lideres-costa-rica-284x284.jpg 284w\" sizes=\"(max-width: 137px) 100vw, 137px\" \/><\/a>En su mayor parte el l\u00edder debe estimular a las personas a adaptarse a los nuevos requerimientos y procedimientos, a implementar ideas nuevas; sin embargo, se encuentran con la dificultar de no lograr envolver a las personas en la propuesta.<\/p>\n<p>Estrategia para generar cambios que involucren <span style=\"text-decoration: underline;\">la voluntad<\/span> de las personas.<\/p>\n<h3>Duraci\u00f3n:<\/h3>\n<p>Dos opciones: 8 horas o 4 horas.<\/p>\n<p>Tambi\u00e9n se pueden adaptar al tiempo y temas que el cliente seleccione.<\/p>\n<h3 style=\"text-align: center;\">Contacto:<\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #3366ff;\">Contacto@psicologialaboral.net<\/span><\/h3>\n<h3 style=\"text-align: center;\">Eduardo G\u00f3mez A.<\/h3>\n<h3 style=\"text-align: center;\">Director y capacitador profesional<\/h3>\n<h2 style=\"text-align: center;\"><span style=\"color: #3366ff;\">Tel: 8312-7000<\/span><\/h2>\n<h3 style=\"text-align: center;\"><span style=\"text-decoration: underline;\">Llame y pida su cotizaci\u00f3n personalizada sin compromisos.<\/span><\/h3>\n<p style=\"text-align: center;\">&nbsp;Curso liderazgo en Costa Rica<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/13.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2205 aligncenter\" alt=\"sinergia capacitacion costa rica\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/13-300x7.png\" width=\"300\" height=\"7\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/13-300x7.png 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/13-170x4.png 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/13-284x7.png 284w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2013\/09\/13.png 650w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>Curso taller de liderazgo Costa Rica Desarrollo de habilidades de liderazgo: L\u00edderes con influencia positiva e inteligencia emocional. Justificaci\u00f3n e importancia de nuestro curso-taller de liderazgo. Generar resultados sobresalientes con las personas&nbsp; no se alcanza desde una posici\u00f3n (ser el jefe, el supervisor, el encargado, etc.), sino desde el nivel de influencia positiva con las<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/2208\/curso-liderazgo-costa-rica\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[58],"class_list":["entry","author-eduardo","post-2208","post","type-post","status-publish","format-standard","has-post-thumbnail","category-motivacion-laboral-2","tag-liderazgo-360"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=2208"}],"version-history":[{"count":8,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2208\/revisions"}],"predecessor-version":[{"id":3230,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/2208\/revisions\/3230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/2209"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=2208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=2208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=2208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}