{"id":1872,"date":"2012-08-18T08:40:34","date_gmt":"2012-08-18T14:40:34","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=1872"},"modified":"2021-02-09T15:53:26","modified_gmt":"2021-02-09T21:53:26","slug":"como-empezar-una-gestion-por-competencias","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/1872\/como-empezar-una-gestion-por-competencias\/","title":{"rendered":"C\u00f3mo empezar una gesti\u00f3n por competencias."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1872\" class=\"elementor elementor-1872\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdcfa52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdcfa52\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60411eb7\" data-id=\"60411eb7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32caccf3 elementor-widget elementor-widget-text-editor\" data-id=\"32caccf3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1874\" title=\"Gesti\u00f3n por competencias diccionario\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/Gesti\u00f3n-por-competencias-diccionario.jpg\" alt=\"\" width=\"700\" height=\"88\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/Gesti\u00f3n-por-competencias-diccionario.jpg 700w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/Gesti\u00f3n-por-competencias-diccionario-300x37.jpg 300w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/Gesti\u00f3n-por-competencias-diccionario-170x21.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/Gesti\u00f3n-por-competencias-diccionario-284x35.jpg 284w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p><p>Una pregunta frecuente que nos realizan es \u00bfc\u00f3mo empezar en mi empresa una gesti\u00f3n por competencias? Bien, indiscutiblemente el primer paso a dar es definir el diccionario de competencias.<\/p><p><strong>Diccionario de competencias.<\/strong><\/p><p>\u00c9ste se refiere a definir las <span style=\"color: #cc0000;\">competencias que se requieren<\/span> para que la organizaci\u00f3n cumpla con las estrategias que han dise\u00f1ado. Por ejemplo, si su empresa vende un servicio, est\u00e1 claro que una competencia requerida en la mayor parte del personal es la <span style=\"text-decoration: underline;\">orientaci\u00f3n al servicio al cliente<\/span>, pues bien, adem\u00e1s de \u00e9sta competencia esta empresa deber\u00e1 \u201csentarse\u201d a definir todas las dem\u00e1s competencias, s\u00ed, exacto\u2026una por una.<\/p><p>Tome en cuenta que existir\u00e1n <strong>competencias gen\u00e9ricas;<\/strong>\u00a0es decir, que son aquellas requeridas para todo el personal a lo largo de la organizaci\u00f3n, estas competencias ayudan a lograr la misi\u00f3n y vis\u00f3n de la organizaci\u00f3n. Por otro lado, los diferentes departamentos o puestos de trabajo tendr\u00e1n las <strong>competencias espec\u00edficas<\/strong>, que igualmente se deber\u00e1n definir.<\/p><p>Ahora bien, el segundo paso de un diccionario de competencias es el definir los <span style=\"text-decoration: underline;\"><strong>4 grados<\/strong><\/span> en que se presenta esa competencia. Es muy importante definirlos.<\/p><p>Para efectos pr\u00e1cticos existen gu\u00edas que ya determinan las competencias y sus niveles, pero es muy importante considerar que si no se adecuan completamente, <span style=\"color: #cc0000;\">se deben personalizar a la organizaci\u00f3n<\/span>.<\/p><p>El siguiente es un ejemplo tomado del libro Selecci\u00f3n por competencias de Martha Alles (2010):<\/p><p style=\"text-align: center;\"><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/diccionario-por-competencias-ejemplo.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"size-full wp-image-1873 aligncenter\" title=\"diccionario por competencias ejemplo\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/diccionario-por-competencias-ejemplo.jpg\" alt=\"\" width=\"461\" height=\"549\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/diccionario-por-competencias-ejemplo.jpg 461w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/diccionario-por-competencias-ejemplo-251x300.jpg 251w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/diccionario-por-competencias-ejemplo-170x202.jpg 170w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2012\/08\/diccionario-por-competencias-ejemplo-284x338.jpg 284w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/><\/a><\/p><p>Si su empresa aun no lleva la gesti\u00f3n por competencias, \u00e9ste es el primer paso que usted puede recomendar, ya que la base de una selecci\u00f3n basada en competencias, evaluaci\u00f3n basada en competencias, promociones, etc. lo es el <strong>diccionario de competencias<\/strong>. Posteriormente se definir\u00e1n en qu\u00e9 nivel debe tener la competencia cada colaborador en los diferentes puestos, si las personas alcanzan los niveles que se definen es cuando son seleccionadas, promovidas o se les brinda el apoyo (capacitaci\u00f3n y desarrollo) para que alcancen el nivel requerido, que esto lo explicaremos en una pr\u00f3xima entrega.<\/p><p>Igualmente sepa que para efectos pr\u00e1cticos ya existen softwares que le ayudan a las empresas a ingresar datos de competencias, sus niveles, por puestos de trabajo, etc. Tales como\u00a0QUERYX 7 , NTC ISO, entre otros.<\/p><p>N\u00f3tese que el ejemplo que ponemos en la fotograf\u00eda es el primer paso: <strong>diccionario de competencias<\/strong>, posterior a este se har\u00e1 el <strong>diccionario de comportamientos<\/strong> que es el que se distribuye en la organizaci\u00f3n y que igualmente explicaremos en otra entrega, con la confecci\u00f3n del diccionario de competencias para empezar es suficiente, ya que este proceso les puede llevar varios d\u00edas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-def2c65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"def2c65\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c48d20\" data-id=\"0c48d20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-277ebbe elementor-widget elementor-widget-image\" data-id=\"277ebbe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-724x1024.jpg\" class=\"attachment-large size-large wp-image-3062\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-724x1024.jpg 724w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-212x300.jpg 212w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/09\/Curso-RHH-VIP-768x1086.jpg 768w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f96578d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f96578d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7cb7f3\" data-id=\"d7cb7f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ed6b44 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0ed6b44\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso Gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-935d015 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"935d015\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d0b1c2e\" data-id=\"d0b1c2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5eabdc elementor-widget elementor-widget-spacer\" data-id=\"a5eabdc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Una pregunta frecuente que nos realizan es \u00bfc\u00f3mo empezar en mi empresa una gesti\u00f3n por competencias? Bien, indiscutiblemente el primer paso a dar es definir el diccionario de competencias. Diccionario de competencias. \u00c9ste se refiere a definir las competencias que se requieren para que la organizaci\u00f3n cumpla con las estrategias que han dise\u00f1ado. Por ejemplo,<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/1872\/como-empezar-una-gestion-por-competencias\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":1875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,48],"tags":[33,40],"class_list":["entry","author-eduardo","post-1872","post","type-post","status-publish","format-standard","has-post-thumbnail","category-capacitacion-recursos-humanos-2","category-gestion-por-competencias-2","tag-competencias-laborales","tag-gestion-por-competencias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/1872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=1872"}],"version-history":[{"count":8,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/1872\/revisions"}],"predecessor-version":[{"id":4029,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/1872\/revisions\/4029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/1875"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=1872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=1872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=1872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}