{"id":1471,"date":"2011-08-28T14:00:07","date_gmt":"2011-08-28T20:00:07","guid":{"rendered":"http:\/\/www.psicologialaboral.net\/articulos\/?p=1471"},"modified":"2021-02-09T16:04:04","modified_gmt":"2021-02-09T22:04:04","slug":"eliminar-el-miedo-en-el-trabajo","status":"publish","type":"post","link":"https:\/\/www.psicologialaboral.net\/articulos\/1471\/eliminar-el-miedo-en-el-trabajo\/","title":{"rendered":"Eliminar el miedo en el trabajo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1471\" class=\"elementor elementor-1471\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64aae58e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64aae58e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-818a95d\" data-id=\"818a95d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d3020ce elementor-widget elementor-widget-text-editor\" data-id=\"7d3020ce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2011\/08\/desmotivaci\u00f3n-trabajo.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-1474\" title=\"desmotivaci\u00f3n trabajo\" src=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2011\/08\/desmotivaci\u00f3n-trabajo-300x235.jpg\" alt=\"\" width=\"257\" height=\"178\" \/><\/a><\/p><p>\u00bfCu\u00e1l es el impacto de <span style=\"color: #cc0000;\"><strong>que los empleados\u00a0que\u00a0realizan el trabajo no opinen<\/strong>,<strong> no innoven,\u00a0ni transfieran sus ideas<\/strong><\/span> a niveles superiores porque saben que los ignoran o minimizan?\u00a0<\/p><p>\u00bfCu\u00e1l es el impacto de que acciones correctivas que se deban implementar <strong>inmediatamente para evitar un atraso o problema mayor<\/strong>, no sean ejecutadas por temor a que posteriormente se les castigue?<\/p><p>\u00a0\u00bfCu\u00e1l es el impacto de que en los entrenamientos, reuniones y capacitaciones el personal sea \u00abun escucha pasivo\u00bb que <span style=\"color: #cc0000;\"><strong>no pregunta ni aclara sus dudas<\/strong><\/span> porque siempre hay un ambiente jocoso entre compa\u00f1eros?<\/p><p><span style=\"color: #cc0000;\"><strong>Si cuantificaramos las consecuencias..\u00bfcu\u00e1n negativo ser\u00eda para el desempe\u00f1o de los grupos?<\/strong><\/span><\/p><p>Te muestro\u00a0las conclusiones\u00a0de una investigaci\u00f3n del Grupo Discovery (Organizaci\u00f3n de encuestas de opini\u00f3n);\u00a0 <strong>sorprendentes resultados<\/strong> a pesar que la intenci\u00f3n de los gerentes y administradores es tener en sus grupos colaboradores proactivos, entusiastas, visionarios, innovadores, etc <span style=\"color: #cc0000;\"><strong>\u2026.!parad\u00f3jico no!<\/strong><\/span><\/p><p>El audio contiene adem\u00e1s, <strong>3 estrategias para eliminar el miedo aplicables tanto en lo laboral como en lo familiar.<\/strong><\/p>[audio:http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2011\/08\/3-pasos-para-eliminar-el-miedo.mp3]<p><br \/><a href=\"http:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2011\/08\/3-pasos-para-eliminar-el-miedo.mp3\">Descarga Audio Aqu\u00ed.<\/a><br \/><br \/><span style=\"color: #cc0000;\"><strong>3 t\u00e9cnicas eficientes para eliminar el miedo en el trabajo:<\/strong><\/span><\/p><p>1-\u00a0\u00a0\u00a0\u00a0\u00a0 Elimine las consecuencias negativas.<\/p><p>2-\u00a0\u00a0\u00a0\u00a0\u00a0 Permita y asegure los procesos de comunicaci\u00f3n.<\/p><p>3-\u00a0\u00a0\u00a0\u00a0\u00a0 Conecte a las personas con su prop\u00f3sito de vida, su prop\u00f3sito laboral.<\/p><p><strong>Ejemplos en el audio.<\/strong><\/p><p>De: Driving fear from the workplace by Dick Richards<\/p><h5 style=\"text-align: center;\">\u00a0<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-644f624 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"644f624\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c4cc932\" data-id=\"c4cc932\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5218e7e elementor-widget elementor-widget-image\" data-id=\"5218e7e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-724x1024.jpg\" class=\"attachment-large size-large wp-image-3026\" alt=\"\" srcset=\"https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-724x1024.jpg 724w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-212x300.jpg 212w, https:\/\/www.psicologialaboral.net\/articulos\/wp-content\/uploads\/2018\/08\/Curso-Gratis-verde-Vip-page-001-768x1086.jpg 768w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfd498d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfd498d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed9fc1a\" data-id=\"ed9fc1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7742408 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7742408\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/home%20\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Curso gratis Haz clic aqu\u00ed<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e398eb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e398eb9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f964868\" data-id=\"f964868\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe8b2bc elementor-widget elementor-widget-spacer\" data-id=\"fe8b2bc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1l es el impacto de que los empleados\u00a0que\u00a0realizan el trabajo no opinen, no innoven,\u00a0ni transfieran sus ideas a niveles superiores porque saben que los ignoran o minimizan?\u00a0 \u00bfCu\u00e1l es el impacto de que acciones correctivas que se deban implementar inmediatamente para evitar un atraso o problema mayor, no sean ejecutadas por temor a que posteriormente<\/p>\n<p class=\"more-link\">\n<a class=\" he-btn\" href=\"https:\/\/www.psicologialaboral.net\/articulos\/1471\/eliminar-el-miedo-en-el-trabajo\/\">Leer m\u00e1s <span class=\"icon\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":1474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,50,63,1],"tags":[85],"class_list":["entry","author-eduardo","post-1471","post","type-post","status-publish","format-standard","has-post-thumbnail","category-administracion-del-talento-humano-2","category-capacitacion-recursos-humanos-2","category-clima-organizacional","category-mandos-medios","tag-cultura-y-clima-organizacional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/1471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/comments?post=1471"}],"version-history":[{"count":13,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/1471\/revisions"}],"predecessor-version":[{"id":4080,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts\/1471\/revisions\/4080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media\/1474"}],"wp:attachment":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/media?parent=1471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories?post=1471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/tags?post=1471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}