{"id":63,"count":27,"description":"","link":"https:\/\/www.psicologialaboral.net\/articulos\/motivacion-y-satisfaccion-laboral\/clima-organizacional\/","name":"Clima organizacional","slug":"clima-organizacional","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.psicologialaboral.net\/articulos\/wp-json\/wp\/v2\/posts?categories=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}